{"id":575,"date":"2016-07-10T18:45:45","date_gmt":"2016-07-10T16:45:45","guid":{"rendered":"https:\/\/www.pdap.de\/?p=575"},"modified":"2021-08-24T13:50:00","modified_gmt":"2021-08-24T11:50:00","slug":"dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen","status":"publish","type":"post","link":"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/","title":{"rendered":"PDAP &#8211; vorbereitet f\u00fcr die Anspr\u00fcche der Qualit\u00e4tssicherung in digitalisierten Unternehmen"},"content":{"rendered":"<p>Das CAQ-System PDAP unterst\u00fctzt die Microsoft Datenplattform&nbsp;ab der Version 2008. Besonders profitiert das System nun aber auch von den M\u00f6glichkeiten, die die neueste Versionen 2016 bietet.<\/p>\n<p>Das Management View Reporting Portal wurde mit dieser Version auf einen modernen HTML 5 Standard gehoben. Das bedeutet eine wesentliche Verbesserung aller ]Darstellungen auf mobilen Ger\u00e4ten, wie insbesondere Tablets. Gleichzeitig wird neben den bekannten Ausgabeformaten wie Word, PDF oder interaktive Excel-Tabelle, nun direkt die Ausgabe nach PowerPoint unterst\u00fctzt. Au\u00dferdem gibt es neue M\u00f6glichkeiten bei der Visualisierung.<\/p>\n<p>Die Schnittstellen erm\u00f6glichen die verst\u00e4rkte Nutzung der Web- und Service basierten Kopplung. &nbsp;Ziel ist die noch tiefere Integration der verschiedenen Systeme. Dabei spielen die Faktoren Security und Performance eine wesentliche Rolle. Kurz gesagt, die M\u00f6glichkeit zur Steuerung wer Zugriff auf welche Daten in welcher Geschwindigkeit erh\u00e4lt, wird immer wichtiger. Besonders wenn es&nbsp;durch Features wie Stretch Database flexibel m\u00f6glich wird Teile der Datenbank bei Bedarf in die Cloud auslagern zu k\u00f6nnen.<\/p>\n<p>Klar ist auch, dass das Thema Sicherheit in diesem Kontext nochmal ganz neue Dimensionen bekommt. Dies unterstreichen die zahlreichen Security-Erweiterungen. Sie reichen von sogenanntem transparenten Data Masking, \u00fcber Row-Level Security, bis hin zu Always Encrypted. Auf jeden Fall wird hier der neue Anspruch an ganzheitlich vernetzten Systeme deutlich.<\/p>\n<p>Wir haben&nbsp;also neben reinen Qulit\u00e4tsthemen auch zunehmend&nbsp;wichtige neue technische Trends aufzugreifen und Anwendungsm\u00f6glichkeiten im Zusammenspiel mit dem CAQ-System PDAP zu&nbsp; beleuchten.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das CAQ-System PDAP unterst\u00fctzt die Microsoft Datenplattform&nbsp;ab der Version 2008. Besonders profitiert das System nun aber auch von den M\u00f6glichkeiten, die die neueste Versionen 2016 bietet. Das Management View Reporting Portal wurde mit dieser Version auf einen modernen HTML 5 Standard gehoben. Das bedeutet eine wesentliche Verbesserung aller ]Darstellungen auf mobilen Ger\u00e4ten, wie insbesondere Tablets. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":577,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[77,43,78],"class_list":["post-575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unternehmen","tag-security","tag-service","tag-sql-server"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PDAP - vorbereitet f\u00fcr die Anspr\u00fcche der Qualit\u00e4tssicherung in digitalisierten Unternehmen &#8211; PDAP - Qualit\u00e4tsmanagement &amp; Digitalisierung<\/title>\n<meta name=\"description\" content=\"Das CAQ-System PDAP unterst\u00fctzt die Microsoft Datenplattform ab der Version 2008. Besonders profitiert das System von der neuesten Versionen 2016.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PDAP - vorbereitet f\u00fcr die Anspr\u00fcche der Qualit\u00e4tssicherung in digitalisierten Unternehmen &#8211; PDAP - Qualit\u00e4tsmanagement &amp; Digitalisierung\" \/>\n<meta property=\"og:description\" content=\"Das CAQ-System PDAP unterst\u00fctzt die Microsoft Datenplattform ab der Version 2008. Besonders profitiert das System von der neuesten Versionen 2016.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/\" \/>\n<meta property=\"og:site_name\" content=\"PDAP - Qualit\u00e4tsmanagement &amp; Digitalisierung\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-10T16:45:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-24T11:50:00+00:00\" \/>\n<meta name=\"author\" content=\"JL-Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pdap.de\\\/en\\\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pdap.de\\\/en\\\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\\\/\"},\"author\":{\"name\":\"JL-Admin\",\"@id\":\"https:\\\/\\\/pdap.de\\\/#\\\/schema\\\/person\\\/b045c121a5b6cfd6c55b7f9840c97744\"},\"headline\":\"PDAP &#8211; vorbereitet f\u00fcr die Anspr\u00fcche der Qualit\u00e4tssicherung in digitalisierten Unternehmen\",\"datePublished\":\"2016-07-10T16:45:45+00:00\",\"dateModified\":\"2021-08-24T11:50:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pdap.de\\\/en\\\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\\\/\"},\"wordCount\":256,\"publisher\":{\"@id\":\"https:\\\/\\\/pdap.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pdap.de\\\/en\\\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Security\",\"Service\",\"SQL Server\"],\"articleSection\":[\"Unternehmen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pdap.de\\\/en\\\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\\\/\",\"url\":\"https:\\\/\\\/pdap.de\\\/en\\\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\\\/\",\"name\":\"PDAP - vorbereitet f\u00fcr die Anspr\u00fcche der Qualit\u00e4tssicherung in digitalisierten Unternehmen &#8211; PDAP - Qualit\u00e4tsmanagement &amp; Digitalisierung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pdap.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pdap.de\\\/en\\\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pdap.de\\\/en\\\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2016-07-10T16:45:45+00:00\",\"dateModified\":\"2021-08-24T11:50:00+00:00\",\"description\":\"Das CAQ-System PDAP unterst\u00fctzt die Microsoft Datenplattform ab der Version 2008. Besonders profitiert das System von der neuesten Versionen 2016.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pdap.de\\\/en\\\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pdap.de\\\/en\\\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pdap.de\\\/en\\\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pdap.de\\\/en\\\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/pdap.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PDAP &#8211; vorbereitet f\u00fcr die Anspr\u00fcche der Qualit\u00e4tssicherung in digitalisierten Unternehmen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pdap.de\\\/#website\",\"url\":\"https:\\\/\\\/pdap.de\\\/\",\"name\":\"PDAP - Qualit\u00e4tsmanagement &amp; Digitalisierung\",\"description\":\"by JessenLenz\",\"publisher\":{\"@id\":\"https:\\\/\\\/pdap.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pdap.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pdap.de\\\/#organization\",\"name\":\"PDAP by JessenLenz\",\"url\":\"https:\\\/\\\/pdap.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pdap.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pdap.de\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/pdap-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/pdap.de\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/pdap-logo-1.png\",\"width\":800,\"height\":377,\"caption\":\"PDAP by JessenLenz\"},\"image\":{\"@id\":\"https:\\\/\\\/pdap.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pdap.de\\\/#\\\/schema\\\/person\\\/b045c121a5b6cfd6c55b7f9840c97744\",\"name\":\"JL-Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f05cf82b703febbb15e71d2522b932a776f7107561efc1a866b0988679d2012?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f05cf82b703febbb15e71d2522b932a776f7107561efc1a866b0988679d2012?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f05cf82b703febbb15e71d2522b932a776f7107561efc1a866b0988679d2012?s=96&d=mm&r=g\",\"caption\":\"JL-Admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PDAP - vorbereitet f\u00fcr die Anspr\u00fcche der Qualit\u00e4tssicherung in digitalisierten Unternehmen &#8211; PDAP - Qualit\u00e4tsmanagement &amp; Digitalisierung","description":"Das CAQ-System PDAP unterst\u00fctzt die Microsoft Datenplattform ab der Version 2008. Besonders profitiert das System von der neuesten Versionen 2016.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/","og_locale":"en_US","og_type":"article","og_title":"PDAP - vorbereitet f\u00fcr die Anspr\u00fcche der Qualit\u00e4tssicherung in digitalisierten Unternehmen &#8211; PDAP - Qualit\u00e4tsmanagement &amp; Digitalisierung","og_description":"Das CAQ-System PDAP unterst\u00fctzt die Microsoft Datenplattform ab der Version 2008. Besonders profitiert das System von der neuesten Versionen 2016.","og_url":"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/","og_site_name":"PDAP - Qualit\u00e4tsmanagement &amp; Digitalisierung","article_published_time":"2016-07-10T16:45:45+00:00","article_modified_time":"2021-08-24T11:50:00+00:00","author":"JL-Admin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/#article","isPartOf":{"@id":"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/"},"author":{"name":"JL-Admin","@id":"https:\/\/pdap.de\/#\/schema\/person\/b045c121a5b6cfd6c55b7f9840c97744"},"headline":"PDAP &#8211; vorbereitet f\u00fcr die Anspr\u00fcche der Qualit\u00e4tssicherung in digitalisierten Unternehmen","datePublished":"2016-07-10T16:45:45+00:00","dateModified":"2021-08-24T11:50:00+00:00","mainEntityOfPage":{"@id":"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/"},"wordCount":256,"publisher":{"@id":"https:\/\/pdap.de\/#organization"},"image":{"@id":"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/#primaryimage"},"thumbnailUrl":"","keywords":["Security","Service","SQL Server"],"articleSection":["Unternehmen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/","url":"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/","name":"PDAP - vorbereitet f\u00fcr die Anspr\u00fcche der Qualit\u00e4tssicherung in digitalisierten Unternehmen &#8211; PDAP - Qualit\u00e4tsmanagement &amp; Digitalisierung","isPartOf":{"@id":"https:\/\/pdap.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/#primaryimage"},"image":{"@id":"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/#primaryimage"},"thumbnailUrl":"","datePublished":"2016-07-10T16:45:45+00:00","dateModified":"2021-08-24T11:50:00+00:00","description":"Das CAQ-System PDAP unterst\u00fctzt die Microsoft Datenplattform ab der Version 2008. Besonders profitiert das System von der neuesten Versionen 2016.","breadcrumb":{"@id":"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/pdap.de\/en\/dap-vorbereitet-fuer-die-anprueche-der-qulitaetssicherung-in-digitalisierten-unternehmen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/pdap.de\/"},{"@type":"ListItem","position":2,"name":"PDAP &#8211; vorbereitet f\u00fcr die Anspr\u00fcche der Qualit\u00e4tssicherung in digitalisierten Unternehmen"}]},{"@type":"WebSite","@id":"https:\/\/pdap.de\/#website","url":"https:\/\/pdap.de\/","name":"PDAP - Qualit\u00e4tsmanagement &amp; Digitalisierung","description":"by JessenLenz","publisher":{"@id":"https:\/\/pdap.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pdap.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pdap.de\/#organization","name":"PDAP by JessenLenz","url":"https:\/\/pdap.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pdap.de\/#\/schema\/logo\/image\/","url":"https:\/\/pdap.de\/wp-content\/uploads\/2021\/08\/pdap-logo-1.png","contentUrl":"https:\/\/pdap.de\/wp-content\/uploads\/2021\/08\/pdap-logo-1.png","width":800,"height":377,"caption":"PDAP by JessenLenz"},"image":{"@id":"https:\/\/pdap.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/pdap.de\/#\/schema\/person\/b045c121a5b6cfd6c55b7f9840c97744","name":"JL-Admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4f05cf82b703febbb15e71d2522b932a776f7107561efc1a866b0988679d2012?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f05cf82b703febbb15e71d2522b932a776f7107561efc1a866b0988679d2012?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f05cf82b703febbb15e71d2522b932a776f7107561efc1a866b0988679d2012?s=96&d=mm&r=g","caption":"JL-Admin"}}]}},"_links":{"self":[{"href":"https:\/\/pdap.de\/en\/wp-json\/wp\/v2\/posts\/575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pdap.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pdap.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pdap.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pdap.de\/en\/wp-json\/wp\/v2\/comments?post=575"}],"version-history":[{"count":1,"href":"https:\/\/pdap.de\/en\/wp-json\/wp\/v2\/posts\/575\/revisions"}],"predecessor-version":[{"id":6991,"href":"https:\/\/pdap.de\/en\/wp-json\/wp\/v2\/posts\/575\/revisions\/6991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pdap.de\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/pdap.de\/en\/wp-json\/wp\/v2\/media?parent=575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pdap.de\/en\/wp-json\/wp\/v2\/categories?post=575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pdap.de\/en\/wp-json\/wp\/v2\/tags?post=575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}